{"id":760,"date":"2001-01-17T09:04:52","date_gmt":"2001-01-17T09:04:52","guid":{"rendered":"https:\/\/www.pfeifer-protocol.com\/de\/?p=760"},"modified":"2016-01-17T09:47:55","modified_gmt":"2016-01-17T09:47:55","slug":"kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs","status":"publish","type":"post","link":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/","title":{"rendered":"Kontroversen in Diagnostik und Therapie beim Prostata Krebs"},"content":{"rendered":"<blockquote><p>Prof. Dr. Dr. med. habil. Ben L. Pfeifer, Lexington, USA<\/p><\/blockquote>\n<p><strong>Zusammenfassung:<\/strong><br \/>\nDieser Beitrag ist kein Versuch, eine umfassende Abhandlung \u00fcber Prostata Krebs zu vermitteln, dazu sind einschl\u00e4gige Textb\u00fccher viel besser geeignet. Hier sollen vielmehr einige Kontroversen und neuere Aspekte in der Diagnostik und Behandlung dieser Krankheit kritisch betrachtet werden, um \u00c4rzte und betroffene Patienten gleicherma\u00dfen anzusto\u00dfen, sich mit den umstrittenen Problemen dieses Krankheitsbildes auseinander zu setzen. Nur mit Sachkenntnis kann man eine individuell optimierte Betreuung erreichen und das Leiden durch Prostata Krebs verringern. Der Krebs der Vorsteherdr\u00fcse ist in den letzten 30 Jahren immer h\u00e4ufiger geworden, und nach dem Lungenkrebs zur zweith\u00e4ufigsten krebsbedingten Todesursache beim Mann aufgestiegen. Wissenschaftler und \u00c4rzte suchen nach immer besseren M\u00f6glichkeiten f\u00fcr Diagnose und Therapie. Eine Ideall\u00f6sung ist dabei sicherlich noch in weiter Ferne, jedoch werden st\u00e4ndig kleine Teilerfolge errungen, die zum Wohle betroffener Patienten eingesetzt werden k\u00f6nnen.<\/p>\n<p><strong>Einleitung:<\/strong><br \/>\nIn den westlichen Industriestaaten steigt die H\u00e4ufigkeit von Prostata Krebs stetig an. In den USA wurden zum Beispiel im Jahre 1993 etwa 165 000 M\u00e4nner mit Prostata Krebs diagnostiziert, im Jahre 1996 waren es bereits 320 000 M\u00e4nner. In Deutschland sind die Verh\u00e4ltnisse \u00e4hnlich, wenn auch durch die geringere Bev\u00f6lkerungszahl die absoluten Zahlen niedriger liegen. Der Anstieg in der H\u00e4ufigkeit wird im wesentlichen als ein Ergebnis einer verbesserten Vorsorgeuntersuchung (\u201cScreening\u201d) mittels prostata-spezifischem Antigen (PSA) angesehen. Da Prostata Krebs vor allem \u00e4ltere M\u00e4nner trifft und sich die Altersstruktur in den meisten westlichen Industriegesellschaften weiterhin in Richtung h\u00f6heres Lebensalter verschiebt, wird die Anzahl der Neuerkrankungen f\u00fcr den h\u00e4ufigsten Krebs des Mannes auch weiterhin ansteigen.<\/p>\n<p>Es ist somit zu erwarten, dass Prostata Krebs zu einem internationalen Gesundheitsproblem heranwachsen und enorme finanzielle Mittel f\u00fcr Diagnostik und Therapie verschlingen wird. Diese Entwicklung ist mehr als besorgniserregend, da wir gegenw\u00e4rtig keine Behandlung f\u00fcr diese Erkrankung kennen,\u00a0 von der wir verl\u00e4sslich wissen, dass sie Heilung herbeif\u00fchren kann, Lebensverl\u00e4ngerung bewirkt, oder wenigsten dem Patienten mehr gutes als schlechtes beschert. Mit diesem Hintergrund wird das Dilemma um Prostata Krebs all zu deutlich. Urologen, Radiologen, und Onkologen werden von einer immer besser informierten und kritischen Schar von Patienten gefordert, sachkundig und ohne Voreingenommenheit f\u00fcr ihre Fachrichtung Auskunft \u00fcber Vor- und Nachteile der verf\u00fcgbaren diagnostischen und therapeutischen M\u00f6glichkeiten zu geben.<\/p>\n<p>Dabei werden die folgenden Fragen immer h\u00e4ufiger gestellt: Welchen Wert hat eine regelm\u00e4\u00dfige Voruntersuchung durch rektales Abtasten der Prostata und gleichzeitige PSA Kontrolle? Kann die Gewebsentnahme (Biopsie) zur Diagnosesicherung vielleicht den Prozess der Krebsaussaat (Metastasierung) beg\u00fcnstigen? Welche Behandlungsmethode ist die beste? Sollte man vielleicht zun\u00e4chst gar nichts tun und abwarten (\u201cWatchful Waiting\u201d)? Was kann sonst noch getan werden, um Prostata Krebs g\u00fcnstig zu beeinflussen? Im Moment haben wir keine abschlie\u00dfenden, wissenschaftlich fundierten Antworten auf diese Fragen. Dieser Beitrag versucht deshalb, durch eine Diskussion von Kontroversen bez\u00fcglich Diagnostik und Therapie bei Prostata Krebs wenigstens einen erneuten Denkansto\u00df all denen zu geben, die sich zum Wohl der Patientengemeinschaft einsetzen.<\/p>\n<p><a class=\"more-link\" href=\"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2016\/01\/2001-PC-Artikel_DE.pdf\" target=\"_blank\" rel=\"\">Artikel weiterlesen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prof. Dr. Dr. med. habil. Ben L. Pfeifer, Lexington, USA Zusammenfassung: Dieser Beitrag ist kein Versuch, eine umfassende Abhandlung \u00fcber Prostata Krebs zu vermitteln, dazu sind einschl\u00e4gige Textb\u00fccher viel besser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,16,7],"tags":[],"class_list":["post-760","post","type-post","status-publish","format-standard","hentry","category-diagnose","category-prostatakrebs","category-veroeffentlichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Kontroversen in Diagnostik und Therapie beim Prostata Krebs - Pfeifer Protokoll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kontroversen in Diagnostik und Therapie beim Prostata Krebs\" \/>\n<meta property=\"og:description\" content=\"Prof. Dr. Dr. med. habil. Ben L. Pfeifer, Lexington, USA Zusammenfassung: Dieser Beitrag ist kein Versuch, eine umfassende Abhandlung \u00fcber Prostata Krebs zu vermitteln, dazu sind einschl\u00e4gige Textb\u00fccher viel besser [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/\" \/>\n<meta property=\"og:site_name\" content=\"Pfeifer Protokoll\" \/>\n<meta property=\"article:published_time\" content=\"2001-01-17T09:04:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-17T09:47:55+00:00\" \/>\n<meta name=\"author\" content=\"Moderator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moderator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\\\/\"},\"author\":{\"name\":\"Moderator\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/6ed9c224c750ac99adf95fbee42d1176\"},\"headline\":\"Kontroversen in Diagnostik und Therapie beim Prostata Krebs\",\"datePublished\":\"2001-01-17T09:04:52+00:00\",\"dateModified\":\"2016-01-17T09:47:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\\\/\"},\"wordCount\":510,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/879d51b33cf494594deb30fbfad836b5\"},\"articleSection\":[\"Diagnose\",\"Prostatakrebs\",\"Ver\u00f6ffentlichungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\\\/\",\"url\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\\\/\",\"name\":\"Kontroversen in Diagnostik und Therapie beim Prostata Krebs - Pfeifer Protokoll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#website\"},\"datePublished\":\"2001-01-17T09:04:52+00:00\",\"dateModified\":\"2016-01-17T09:47:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kontroversen in Diagnostik und Therapie beim Prostata Krebs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/\",\"name\":\"Pfeifer Protokoll\",\"description\":\"Erfolgreiche Kombination von konventioneller und komplement\u00e4rer Krebstherapie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/879d51b33cf494594deb30fbfad836b5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/879d51b33cf494594deb30fbfad836b5\",\"name\":\"BPF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo.png\",\"url\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo.png\",\"width\":480,\"height\":96,\"caption\":\"BPF\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo.png\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/6ed9c224c750ac99adf95fbee42d1176\",\"name\":\"Moderator\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Kontroversen in Diagnostik und Therapie beim Prostata Krebs - Pfeifer Protokoll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/","og_locale":"de_DE","og_type":"article","og_title":"Kontroversen in Diagnostik und Therapie beim Prostata Krebs","og_description":"Prof. Dr. Dr. med. habil. Ben L. Pfeifer, Lexington, USA Zusammenfassung: Dieser Beitrag ist kein Versuch, eine umfassende Abhandlung \u00fcber Prostata Krebs zu vermitteln, dazu sind einschl\u00e4gige Textb\u00fccher viel besser [&hellip;]","og_url":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/","og_site_name":"Pfeifer Protokoll","article_published_time":"2001-01-17T09:04:52+00:00","article_modified_time":"2016-01-17T09:47:55+00:00","author":"Moderator","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Moderator","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/#article","isPartOf":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/"},"author":{"name":"Moderator","@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/6ed9c224c750ac99adf95fbee42d1176"},"headline":"Kontroversen in Diagnostik und Therapie beim Prostata Krebs","datePublished":"2001-01-17T09:04:52+00:00","dateModified":"2016-01-17T09:47:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/"},"wordCount":510,"publisher":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/879d51b33cf494594deb30fbfad836b5"},"articleSection":["Diagnose","Prostatakrebs","Ver\u00f6ffentlichungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/","url":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/","name":"Kontroversen in Diagnostik und Therapie beim Prostata Krebs - Pfeifer Protokoll","isPartOf":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/#website"},"datePublished":"2001-01-17T09:04:52+00:00","dateModified":"2016-01-17T09:47:55+00:00","breadcrumb":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pfeifer-protocol.com\/de\/kontroversen-in-diagnostik-und-therapie-beim-prostata-krebs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pfeifer-protocol.com\/de\/"},{"@type":"ListItem","position":2,"name":"Kontroversen in Diagnostik und Therapie beim Prostata Krebs"}]},{"@type":"WebSite","@id":"https:\/\/www.pfeifer-protocol.com\/de\/#website","url":"https:\/\/www.pfeifer-protocol.com\/de\/","name":"Pfeifer Protokoll","description":"Erfolgreiche Kombination von konventioneller und komplement\u00e4rer Krebstherapie","publisher":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/879d51b33cf494594deb30fbfad836b5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pfeifer-protocol.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/879d51b33cf494594deb30fbfad836b5","name":"BPF","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2016\/01\/Logo.png","url":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2016\/01\/Logo.png","contentUrl":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2016\/01\/Logo.png","width":480,"height":96,"caption":"BPF"},"logo":{"@id":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2016\/01\/Logo.png"}},{"@type":"Person","@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/6ed9c224c750ac99adf95fbee42d1176","name":"Moderator"}]}},"_links":{"self":[{"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/posts\/760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/comments?post=760"}],"version-history":[{"count":4,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/posts\/760\/revisions"}],"predecessor-version":[{"id":769,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/posts\/760\/revisions\/769"}],"wp:attachment":[{"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/media?parent=760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/categories?post=760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/tags?post=760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}