{"id":369,"date":"2014-10-26T16:37:15","date_gmt":"2014-10-26T16:37:15","guid":{"rendered":"https:\/\/www.pfeifer-protocol.com\/?p=369"},"modified":"2014-10-26T16:44:25","modified_gmt":"2014-10-26T16:44:25","slug":"prostatitis","status":"publish","type":"post","link":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/","title":{"rendered":"Prostatitis"},"content":{"rendered":"<h4><strong>Zusammenfassung<\/strong><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-371\" src=\"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis.png\" alt=\"Prostatitis\" width=\"244\" height=\"240\" srcset=\"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis.png 244w, https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis-90x90.png 90w, https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis-75x75.png 75w\" sizes=\"auto, (max-width: 244px) 100vw, 244px\" \/>Die Prostatitis ist ein Sammelbegriff f\u00fcr Beschwerden im Bereich der Vorsteherdr\u00fcse und der benachbarten K\u00f6rperregionen, also dem Dammbereich, dem Anus, dem Enddarm, dem Hoden oder der Leistenbeuge. Etwa 30% der M\u00e4nner im Alter zwischen 20 und 40 Jahren leiden gelegentlich unter Prostatabeschwerden Man kann die Prostatitis grob in zwei Gruppen einteilen: die bakterielle Prostatitis, also die durch Bakterien verursachte Prostatitis und die abakterielle Prostatitis, die nicht durch Bakterien verursacht wird. Die bakterielle Prostatitis in der akuten und chronischen Form entsteht durch Bakterien, die in die Prostata eindringen und eine Infektion ausl\u00f6sen. Die Behandlung erfolgt in der Regel Antibiotisch. Bei der abakteriellen Prostatitis unterscheidet man das entz\u00fcndliche vom nicht-entz\u00fcndlichen chronischen Schmerzsyndrom des Beckens. Bei beiden m\u00fcssen organische und bakterielle Ursachen ausgeschlossen werden. Die Behandlung orientiert sich an den Beschwerden des Patienten und kann oft langwierig und schwierig sein.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Einteilung und Ursachen<\/strong><\/h4>\n<p>Man unterscheidet die bakterielle Prostatitis von der abakteriellen Prostatitis. Bei der bakteriellen Prostatitis sind Bakterien urs\u00e4chlich f\u00fcr die Prostataentz\u00fcndung verantwortlich. Meist gelangen diese \u00fcber die Harnr\u00f6hre in die Prostata. Oft handelt es sich um Darmbakterien (E. coli, Enteroccocus faecalis), die in die Harnr\u00f6hre aufsteigen und die Harnr\u00f6hrenschleimhaut und die Prostata befallen. Beg\u00fcnstigend daf\u00fcr wirkt eine Blasenauslassverengung durch eine gutartige Prostatavergr\u00f6\u00dferung oder eine \u00a0Harnr\u00f6hrenenge. Durch die Blasenauslassverengung kommt es beim Wasserlassen zu einer Druckerh\u00f6hung im unteren Harntrakt, wodurch die Bakterien in das Prostatagewebe leichter hineingelangen k\u00f6nnen (prostatischer Reflux). Seltener k\u00f6nnen Bakterien aus anderen infizierten K\u00f6rperregionen auf dem Blutwege in die Prostata gelangen und dort eine Infektion ausl\u00f6sen.<\/p>\n<p>Bei der abakteriellen Prostatitis unterscheidet man das entz\u00fcndliche vom nicht-entz\u00fcndlichen chronischen Schmerzsyndrom des Beckens. Das entz\u00fcndliche chronische Schmerzsyndrom des Beckens unterscheidet sich nicht von den Symptomen der chronischen bakteriellen Prostatitis, als Ursache k\u00f6nnen aber keine Bakterien als Erreger nachgewiesen werden.<\/p>\n<p>Nachgewiesen werden wei\u00dfe Blutk\u00f6rperchen in der Prostatafl\u00fcssigkeit und im Sperma. Als Ursachen nimmt man Blasenentleerungsst\u00f6rungen und den oben beschriebenen prostatischen Reflux an. Dabei gelangt Urin in die Prostatadr\u00fcseng\u00e4nge, wodurch sich Stoffwechselprodukte (Harns\u00e4ure, Purin- und Pyrimidinbasen) im Prostatagewebe ablagern und zu Entz\u00fcndungen und Prostatasteinen f\u00fchren.<\/p>\n<p>Das nicht-entz\u00fcndliche chronische Schmerzsyndrom des Beckens wird auch als \u201eProstatodynie\u201c oder \u201eProstatopathie\u201c bezeichnet. Da organische Ursachen f\u00fcr die Schmerzsymptome nicht nachweisbar sind, vermutet man haupts\u00e4chlich psychosomatische Ursachen. Insbesondere werden Stress, \u00c4ngste, Entt\u00e4uschung, Wut, l\u00e4nger bestehende Partner- bzw. Sexualprobleme f\u00fcr unbewusste Muskelspannungen in der Beckenregion verantwortlich gemacht, die dann zu den Prostatitis &#8211; Symptomen f\u00fchren k\u00f6nnen.<\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Diagnosen und Therapien<\/strong><\/h4>\n<p><strong>Akute bakterielle Prostatitis<\/strong><\/p>\n<p>Die akute bakterielle Prostatitis ist leicht zu diagnostizieren und ist gut behandelbar. Brennen beim Wasserlassen, h\u00e4ufiges Wasserlassen, Schmerzen in der Blasenregion und im Dammbereich und zus\u00e4tzlich Fieber und Sch\u00fcttelfrost sind die typischen Zeichen einer akuten bakteriellen Prostatitis. Der Urologe tastet bei der Untersuchung durch den Enddarm eine \u00e4u\u00dferst druckschmerzhafte Prostata. Der Urin ist entz\u00fcndlich ver\u00e4ndert, er enth\u00e4lt Leukozyten und Bakterien. Unter einer Antibiotika &#8211; Therapie erreicht man rasche Besserung.<\/p>\n<p>Gelegentlich kommt es auch zur Harnverhaltung, d.h. die Blase kann nicht mehr entleert werden. Man ist dann gezwungen den Urin \u00fcber einen Katheter abzuleiten.<br \/>\n<strong>Prostataabszess<\/strong><\/p>\n<p>Aus der akuten bakteriellen Prostatitis kann ein Prostataabszess (Eiteransammlung in der Prostata) entstehen. Durch das Abtasten der Prostata und die Ultraschalluntersuchung mit einer speziellen Enddarmsonde kann die Diagnose sicher gestellt werden. Hochdosierte Antibiotikatherapie und chirurgische Ma\u00dfnahmen (Er\u00f6ffnung und Ableitung des Abszesses) sind die Basis der erfolgreichen Therapie.<br \/>\n<strong>Chronische bakterielle Prostatitis<\/strong><\/p>\n<p>Bei der chronischen bakteriellen Prostatitis bildet sich aus einer akuten bakteriellen Prostatitis eine wiederkehrende (chronische) Entz\u00fcndung aus. Wenn nach der Behandlung einer Prostataentz\u00fcndung trotz intensiver Antibiotikatherapie in den Dr\u00fcsenarealen der Prostata Bakterien zur\u00fcckbleiben, k\u00f6nnen diese in der Folge in unregelm\u00e4\u00dfigen Abst\u00e4nden erneute Infektionen verursachen.<\/p>\n<p>Die chronisch bakterielle Prostatitis bietet ein buntes Bild von Symptomen: Brennen in der Harnr\u00f6hre nach dem Harnlassen, Druckgef\u00fchl und\/oder Schmerzen in der Schambeinregion und Unterbauch, Druckgef\u00fchl und Schmerzen im Dammbereich, Missempfindungen bzw. Schmerzen in den Hoden, Blut im Sperma, Schmerzhafter Samenerguss, Schmerzen in der Blasenregion nach dem Wasserlassen, diffuse Unterleibschmerzen, Ziehen und Schmerzen in der Leiste, h\u00e4ufiger Harndrang.<\/p>\n<p>Aus der Prostatafl\u00fcssigkeit, welche durch Ausmassieren der Prostata durch den Enddarm gewonnen wird, und aus Sperma k\u00f6nnen Bakterien als Krankheitserreger erkannt werden. Gleichzeitig k\u00f6nnen Entz\u00fcndungszeichen (Leukozyten) in Prostatafl\u00fcssigkeit oder Sperma festgestellt warden.<\/p>\n<p>Die chronische bakterielle Prostatitis macht eine \u00fcber einen l\u00e4ngere Zeitraum andauernde Antibiotikatherapie (4 Wochen-3 Monate) notwendig. Durch die mit Antibiotika schwer erreichbaren Prostataregionen und Prostataverkalkungen wird die Therapie erheblich erschwert. Leider konnten die Behandlungserfolge durch direktes Einbringen von Antibiotika in die Prostatadr\u00fcse nicht wesentlich verbessert werden. Die Aussch\u00e4lung der Prostata mittels eines operativen Eingriffs, bei der das gesamte entz\u00fcndlich ver\u00e4nderte Gewebe chirurgisch entfernt wird, bleibt bei immer wiederkehrenden Entz\u00fcndungen als letzte Behandlungsm\u00f6glichkeit.<br \/>\n<strong>Abakterielle Prostatitis<\/strong><\/p>\n<p>Die abakterielle Prostatitis ist die bei weitem h\u00e4ufigste aller Prostatitisformen (90%). Aufgrund der immer noch nicht ausreichend verstandenen Ursachen gibt es keine standardisierte Therapie. Das erkl\u00e4rt auch die Vielzahl wissenschaftlich nicht untersuchter Therapiekonzepte. Man unterscheidet das entz\u00fcndliche vom nicht entz\u00fcndlichen chronischen Schmerzsyndrom des Beckens.<br \/>\n<strong>Entz\u00fcndliches chronisches Schmerzsyndrom des Beckens<\/strong><\/p>\n<p>Dieses Krankheitsbild unterscheidet sich nicht von den Symptomen der chronischen bakteriellen Prostatitis, als Ursache k\u00f6nnen aber keine Bakterien als Erreger nachgewiesen werden. Nachgewiesen werden Leukozyten im Prostatasekret und im Sperma. Die Phytotherapie (pflanzliche Medikamente: z.B. Roggenpollenextrakt, K\u00fcrbiskerne) wird \u00a0hierbei sehr h\u00e4ufig angewandt und f\u00fchrt oft zu einer dauerhaften Linderung der Beschwerden. Die medikament\u00f6se Verbesserung des Urinflusses (Alphablocker) f\u00fchrt meistens ebenfalls zu einer Verminderung der Symptome insbesondere wird der h\u00e4ufige Harndrang besser beherrscht. Die Thermotherapie, die als Alternativmethode zur Behandlung der gutartigen Prostata zur Anwendung kommt, wird auch bei abakterieller Prostatitis eingesetzt, aussagekr\u00e4ftige Studien stehen allerdings noch aus. Durch die Gabe von Allopurinol soll die Verminderung der Harnstoffabbauprodukte im Urin erreicht werden, was zu einer Senkung der Prostatabeschwerden f\u00fchren soll. Auch entz\u00fcndungshemmende Medikamente (Antiphlogistika) kommen, wenn auch umstritten, zum Einsatz. Die regelm\u00e4\u00dfige Ejakulation, die bei Prostatitis h\u00e4ufig aufgrund der Schmerzen vermieden wird, wird empfohlen. In diese Behandlungskategorie geh\u00f6rt auch die Prostatamassage. Der Hintergrund f\u00fcr diese Behandlung bildet die Vorstellung, dass der Sp\u00fcleffekt durch die austretende Prostatafl\u00fcssigkeit die Ausheilung beg\u00fcnstigt, wissenschaftliche Untersuchungen fehlen auch hier.<br \/>\n<strong>Nicht-entz\u00fcndliches chronisches Schmerzsyndrom des Beckens<\/strong><\/p>\n<p>Das nicht-entz\u00fcndliche chronische Schmerzsyndrom des Beckens wird auch als &#8222;Prostatodynie&#8220; oder &#8222;Prostatopathie&#8220; bezeichnet. Die Symptome unterschieden sich nicht wesentlich von denen des entz\u00fcndlichen chronischen Schmerzsyndroms des Beckens.<\/p>\n<p>Allerdings l\u00e4sst sich in den durchgef\u00fchrten Untersuchungen eine entz\u00fcndliche Ursache nicht nachweisen. Behandlungsempfehlungen sind eingehende therapeutische Gespr\u00e4che, die den seelischen Hintergrund des Leidens aufdecken sollen und die physikalische Therapie: W\u00e4rmeanwendungen (Sitzb\u00e4der), leichtes Joggen zur Entspannung der Beckenbodenmuskulatur, Muskelentspannungs\u00fcbungen sowie autogenes Training. Es k\u00f6nnen aber auch Erkrankungen aus angrenzenden K\u00f6rperregionen urs\u00e4chlich f\u00fcr die Prostatabeschwerden verantwortlich sein, z.B. H\u00e4morrhoiden, Probleme im Enddarmbereich, Analfissuren aber auch Nervenst\u00f6rungen an den Muskeln im Blasen- und Beckenbodenbereich sowie Blasenhalsverh\u00e4rtungen ebenso wie Tumore der Harnblase oder der Prostata. Daher sollte immer eine sorgf\u00e4ltige organische Abkl\u00e4rung durch einen Urologen erfolgen, bevor die Diagnose eines chronischen Schmerzsyndroms des Beckens gestellt wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zusammenfassung Die Prostatitis ist ein Sammelbegriff f\u00fcr Beschwerden im Bereich der Vorsteherdr\u00fcse und der benachbarten K\u00f6rperregionen, also dem Dammbereich, dem Anus, dem Enddarm, dem Hoden oder der Leistenbeuge. Etwa 30% [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,7],"tags":[],"class_list":["post-369","post","type-post","status-publish","format-standard","hentry","category-prostatitis","category-veroeffentlichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Prostatitis - Pfeifer Protokoll<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prostatitis\" \/>\n<meta property=\"og:description\" content=\"Zusammenfassung Die Prostatitis ist ein Sammelbegriff f\u00fcr Beschwerden im Bereich der Vorsteherdr\u00fcse und der benachbarten K\u00f6rperregionen, also dem Dammbereich, dem Anus, dem Enddarm, dem Hoden oder der Leistenbeuge. Etwa 30% [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/\" \/>\n<meta property=\"og:site_name\" content=\"Pfeifer Protokoll\" \/>\n<meta property=\"article:published_time\" content=\"2014-10-26T16:37:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-10-26T16:44:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis.png\" \/>\n<meta name=\"author\" content=\"Moderator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Moderator\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/\"},\"author\":{\"name\":\"Moderator\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/6ed9c224c750ac99adf95fbee42d1176\"},\"headline\":\"Prostatitis\",\"datePublished\":\"2014-10-26T16:37:15+00:00\",\"dateModified\":\"2014-10-26T16:44:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/\"},\"wordCount\":1219,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/879d51b33cf494594deb30fbfad836b5\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/prostatitis.png\",\"articleSection\":[\"Prostatitis\",\"Ver\u00f6ffentlichungen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/\",\"url\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/\",\"name\":\"Prostatitis - Pfeifer Protokoll\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/prostatitis.png\",\"datePublished\":\"2014-10-26T16:37:15+00:00\",\"dateModified\":\"2014-10-26T16:44:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/prostatitis.png\",\"contentUrl\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/prostatitis.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/prostatitis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prostatitis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/\",\"name\":\"Pfeifer Protokoll\",\"description\":\"Erfolgreiche Kombination von konventioneller und komplement\u00e4rer Krebstherapie\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/879d51b33cf494594deb30fbfad836b5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/879d51b33cf494594deb30fbfad836b5\",\"name\":\"BPF\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo.png\",\"url\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo.png\",\"contentUrl\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo.png\",\"width\":480,\"height\":96,\"caption\":\"BPF\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Logo.png\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pfeifer-protocol.com\\\/de\\\/#\\\/schema\\\/person\\\/6ed9c224c750ac99adf95fbee42d1176\",\"name\":\"Moderator\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Prostatitis - Pfeifer Protokoll","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/","og_locale":"de_DE","og_type":"article","og_title":"Prostatitis","og_description":"Zusammenfassung Die Prostatitis ist ein Sammelbegriff f\u00fcr Beschwerden im Bereich der Vorsteherdr\u00fcse und der benachbarten K\u00f6rperregionen, also dem Dammbereich, dem Anus, dem Enddarm, dem Hoden oder der Leistenbeuge. Etwa 30% [&hellip;]","og_url":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/","og_site_name":"Pfeifer Protokoll","article_published_time":"2014-10-26T16:37:15+00:00","article_modified_time":"2014-10-26T16:44:25+00:00","og_image":[{"url":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis.png","type":"","width":"","height":""}],"author":"Moderator","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Moderator","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/#article","isPartOf":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/"},"author":{"name":"Moderator","@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/6ed9c224c750ac99adf95fbee42d1176"},"headline":"Prostatitis","datePublished":"2014-10-26T16:37:15+00:00","dateModified":"2014-10-26T16:44:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/"},"wordCount":1219,"publisher":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/879d51b33cf494594deb30fbfad836b5"},"image":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis.png","articleSection":["Prostatitis","Ver\u00f6ffentlichungen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/","url":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/","name":"Prostatitis - Pfeifer Protokoll","isPartOf":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/#primaryimage"},"image":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis.png","datePublished":"2014-10-26T16:37:15+00:00","dateModified":"2014-10-26T16:44:25+00:00","breadcrumb":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/#primaryimage","url":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis.png","contentUrl":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2014\/10\/prostatitis.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pfeifer-protocol.com\/de\/prostatitis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pfeifer-protocol.com\/de\/"},{"@type":"ListItem","position":2,"name":"Prostatitis"}]},{"@type":"WebSite","@id":"https:\/\/www.pfeifer-protocol.com\/de\/#website","url":"https:\/\/www.pfeifer-protocol.com\/de\/","name":"Pfeifer Protokoll","description":"Erfolgreiche Kombination von konventioneller und komplement\u00e4rer Krebstherapie","publisher":{"@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/879d51b33cf494594deb30fbfad836b5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pfeifer-protocol.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/879d51b33cf494594deb30fbfad836b5","name":"BPF","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2016\/01\/Logo.png","url":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2016\/01\/Logo.png","contentUrl":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2016\/01\/Logo.png","width":480,"height":96,"caption":"BPF"},"logo":{"@id":"https:\/\/www.pfeifer-protocol.com\/wp-content\/uploads\/2016\/01\/Logo.png"}},{"@type":"Person","@id":"https:\/\/www.pfeifer-protocol.com\/de\/#\/schema\/person\/6ed9c224c750ac99adf95fbee42d1176","name":"Moderator"}]}},"_links":{"self":[{"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/posts\/369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/comments?post=369"}],"version-history":[{"count":3,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/posts\/369\/revisions"}],"predecessor-version":[{"id":373,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/posts\/369\/revisions\/373"}],"wp:attachment":[{"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/media?parent=369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/categories?post=369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pfeifer-protocol.com\/de\/wp-json\/wp\/v2\/tags?post=369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}